{"id":836,"count":3,"description":"","link":"https:\/\/travelincrete.com\/nl\/tour-category\/culinaire-rondleidingen\/","name":"Culinaire rondleidingen","slug":"culinaire-rondleidingen","taxonomy":"tour_category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vind de beste Deals voor Culinaire rondleidingen - `Boek Culinaire rondleidingen op Kreta<\/title>\n<meta name=\"description\" content=\"De beste deals voor Culinaire rondleidingen vind je op Travel in Crete. Bezoek onze website voor alle Culinaire rondleidingen aanbiedingen. Boek tours en trips op Kreta.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/travelincrete.com\/nl\/tour-category\/culinaire-rondleidingen\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vind de beste Deals voor Culinaire rondleidingen - `Boek Culinaire rondleidingen op Kreta\" \/>\n<meta property=\"og:description\" content=\"De beste deals voor Culinaire rondleidingen vind je op Travel in Crete. Bezoek onze website voor alle Culinaire rondleidingen aanbiedingen. Boek tours en trips op Kreta.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/travelincrete.com\/nl\/tour-category\/culinaire-rondleidingen\/\" \/>\n<meta property=\"og:site_name\" content=\"Travel in Crete\" \/>\n<meta property=\"og:image\" content=\"https:\/\/travelincrete.com\/wp-content\/uploads\/2022\/09\/travelincrete-header.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@travelincrete\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/travelincrete.com\\\/nl\\\/tour-category\\\/culinaire-rondleidingen\\\/\",\"url\":\"https:\\\/\\\/travelincrete.com\\\/nl\\\/tour-category\\\/culinaire-rondleidingen\\\/\",\"name\":\"Vind de beste Deals voor Culinaire rondleidingen - `Boek Culinaire rondleidingen op Kreta\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/travelincrete.com\\\/nl\\\/#website\"},\"description\":\"De beste deals voor Culinaire rondleidingen vind je op Travel in Crete. Bezoek onze website voor alle Culinaire rondleidingen aanbiedingen. Boek tours en trips op Kreta.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/travelincrete.com\\\/nl\\\/tour-category\\\/culinaire-rondleidingen\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/travelincrete.com\\\/nl\\\/tour-category\\\/culinaire-rondleidingen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/travelincrete.com\\\/nl\\\/homepage\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Culinaire rondleidingen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/travelincrete.com\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/travelincrete.com\\\/nl\\\/\",\"name\":\"Travel in Crete\",\"description\":\"Book tours and trips\",\"publisher\":{\"@id\":\"https:\\\/\\\/travelincrete.com\\\/nl\\\/#organization\"},\"alternateName\":\"TiC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/travelincrete.com\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/travelincrete.com\\\/nl\\\/#organization\",\"name\":\"Travel in Crete\",\"alternateName\":\"TIC\",\"url\":\"https:\\\/\\\/travelincrete.com\\\/nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/travelincrete.com\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/travelincrete.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/travel-in-crete-logo-3-1.png\",\"contentUrl\":\"https:\\\/\\\/travelincrete.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/travel-in-crete-logo-3-1.png\",\"width\":195,\"height\":68,\"caption\":\"Travel in Crete\"},\"image\":{\"@id\":\"https:\\\/\\\/travelincrete.com\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/travelincretecom\\\/\",\"https:\\\/\\\/x.com\\\/travelincrete\",\"https:\\\/\\\/instagram.com\\\/travelincrete.gr\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vind de beste Deals voor Culinaire rondleidingen - `Boek Culinaire rondleidingen op Kreta","description":"De beste deals voor Culinaire rondleidingen vind je op Travel in Crete. Bezoek onze website voor alle Culinaire rondleidingen aanbiedingen. Boek tours en trips op Kreta.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/travelincrete.com\/nl\/tour-category\/culinaire-rondleidingen\/","og_locale":"nl_NL","og_type":"article","og_title":"Vind de beste Deals voor Culinaire rondleidingen - `Boek Culinaire rondleidingen op Kreta","og_description":"De beste deals voor Culinaire rondleidingen vind je op Travel in Crete. Bezoek onze website voor alle Culinaire rondleidingen aanbiedingen. Boek tours en trips op Kreta.","og_url":"https:\/\/travelincrete.com\/nl\/tour-category\/culinaire-rondleidingen\/","og_site_name":"Travel in Crete","og_image":[{"width":1920,"height":1080,"url":"https:\/\/travelincrete.com\/wp-content\/uploads\/2022\/09\/travelincrete-header.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_site":"@travelincrete","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/travelincrete.com\/nl\/tour-category\/culinaire-rondleidingen\/","url":"https:\/\/travelincrete.com\/nl\/tour-category\/culinaire-rondleidingen\/","name":"Vind de beste Deals voor Culinaire rondleidingen - `Boek Culinaire rondleidingen op Kreta","isPartOf":{"@id":"https:\/\/travelincrete.com\/nl\/#website"},"description":"De beste deals voor Culinaire rondleidingen vind je op Travel in Crete. Bezoek onze website voor alle Culinaire rondleidingen aanbiedingen. Boek tours en trips op Kreta.","breadcrumb":{"@id":"https:\/\/travelincrete.com\/nl\/tour-category\/culinaire-rondleidingen\/#breadcrumb"},"inLanguage":"nl-NL"},{"@type":"BreadcrumbList","@id":"https:\/\/travelincrete.com\/nl\/tour-category\/culinaire-rondleidingen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/travelincrete.com\/nl\/homepage\/"},{"@type":"ListItem","position":2,"name":"Culinaire rondleidingen"}]},{"@type":"WebSite","@id":"https:\/\/travelincrete.com\/nl\/#website","url":"https:\/\/travelincrete.com\/nl\/","name":"Travel in Crete","description":"Book tours and trips","publisher":{"@id":"https:\/\/travelincrete.com\/nl\/#organization"},"alternateName":"TiC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/travelincrete.com\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/travelincrete.com\/nl\/#organization","name":"Travel in Crete","alternateName":"TIC","url":"https:\/\/travelincrete.com\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/travelincrete.com\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/travelincrete.com\/wp-content\/uploads\/2022\/09\/travel-in-crete-logo-3-1.png","contentUrl":"https:\/\/travelincrete.com\/wp-content\/uploads\/2022\/09\/travel-in-crete-logo-3-1.png","width":195,"height":68,"caption":"Travel in Crete"},"image":{"@id":"https:\/\/travelincrete.com\/nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/travelincretecom\/","https:\/\/x.com\/travelincrete","https:\/\/instagram.com\/travelincrete.gr"]}]}},"_links":{"self":[{"href":"https:\/\/travelincrete.com\/nl\/wp-json\/wp\/v2\/tour_category\/836","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/travelincrete.com\/nl\/wp-json\/wp\/v2\/tour_category"}],"about":[{"href":"https:\/\/travelincrete.com\/nl\/wp-json\/wp\/v2\/taxonomies\/tour_category"}],"wp:post_type":[{"href":"https:\/\/travelincrete.com\/nl\/wp-json\/wp\/v2\/tour?tour_category=836"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}